{"id":2894,"count":0,"description":"","link":"https:\/\/it.telkomuniversity.ac.id\/en\/tag\/ethernethub-en\/","name":"EthernetHub","slug":"ethernethub-en","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/it.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/tags\/2894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/it.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/it.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/posts?tags=2894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}